{"id":3267,"date":"2026-05-13T02:58:38","date_gmt":"2026-05-13T02:58:38","guid":{"rendered":"https:\/\/reclone.org\/?p=3267"},"modified":"2026-05-13T02:59:55","modified_gmt":"2026-05-13T02:59:55","slug":"reclone-starter-kits-serao-distribuidos-em-13-paises-da-america-latina","status":"publish","type":"post","link":"https:\/\/reclone.org\/es\/reclone-starter-kits-serao-distribuidos-em-13-paises-da-america-latina\/","title":{"rendered":"Reclone Starter Kits ser\u00e3o distribu\u00eddos em 13 pa\u00edses da Am\u00e9rica Latina"},"content":{"rendered":"<p>Em mar\u00e7o de 2026, a Reclone lan\u00e7ou uma chamada aberta para os Latin America Starter Kits, com o objetivo de ampliar o acesso a ferramentas de biologia molecular, recursos educacionais e pr\u00e1ticas de biotecnologia aberta em toda a regi\u00e3o. Ap\u00f3s uma resposta expressiva da comunidade, com mais de 150 inscri\u00e7\u00f5es recebidas, temos o prazer de anunciar que 135 participantes de 13 pa\u00edses da Am\u00e9rica Latina foram selecionados para receber os kits.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"467\" src=\"https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/13-1024x467.png\" alt=\"\" class=\"wp-image-3253\" srcset=\"https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/13-1024x467.png 1024w, https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/13-300x137.png 300w, https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/13-768x350.png 768w, https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/13-1536x700.png 1536w, https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/13-18x8.png 18w, https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/13.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A chamada recebeu inscri\u00e7\u00f5es de estudantes, pesquisadores, educadores, membros de laborat\u00f3rios comunit\u00e1rios e empreendedores atuando em uma ampla variedade de \u00e1reas e institui\u00e7\u00f5es. A forte resposta demonstrou n\u00e3o apenas o crescente interesse em biologia sint\u00e9tica e molecular na Am\u00e9rica Latina, mas tamb\u00e9m a necessidade urgente de maior acesso a infraestrutura, oportunidades de capacita\u00e7\u00e3o e redes regionais de colabora\u00e7\u00e3o.<\/p>\n\n\n\n<p>Os participantes selecionados est\u00e3o baseados na Argentina, Bol\u00edvia, Brasil, Chile, Col\u00f4mbia, Costa Rica, Equador, Guatemala, M\u00e9xico, Panam\u00e1, Paraguai, Peru e Uruguai. Juntos, eles representam universidades, institutos de pesquisa, startups, laborat\u00f3rios comunit\u00e1rios e organiza\u00e7\u00f5es sem fins lucrativos em toda a regi\u00e3o.<\/p>\n\n\n\n<iframe src=\"https:\/\/www.google.com\/maps\/d\/embed?mid=1_agrbTc8shdlrstKaPc6PMjImVBLXV4&#038;ehbc=2E312F\" width=\"850\" height=\"480\"><\/iframe>\n\n\n\n<p>Os Reclone Starter Kits foram projetados como uma porta de entrada para pessoas interessadas em desenvolver experi\u00eancia pr\u00e1tica com fluxos de trabalho em biologia molecular e sint\u00e9tica. Al\u00e9m de receberem os materiais, os participantes passam a integrar uma rede regional mais ampla focada em ci\u00eancia aberta, compartilhamento de conhecimento e desenvolvimento de biotecnologia liderado pela comunidade.<\/p>\n\n\n\n<p>Cada Starter Kit cont\u00e9m 10 plasm\u00eddeos liofilizados que codificam enzimas e prote\u00ednas comumente utilizadas em biologia molecular e no ensino. Entre eles est\u00e3o constru\u00e7\u00f5es de DNA para enzimas de PCR (Pfu-Ssod7, Taq e OpenVent), transcriptase reversa oMMLV e a polimerase Bst-LF para aplica\u00e7\u00f5es de LAMP. O kit tamb\u00e9m inclui constru\u00e7\u00f5es de prote\u00ednas fluorescentes que podem ser usadas em atividades de ensino de express\u00e3o e purifica\u00e7\u00e3o de prote\u00ednas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"464\" src=\"https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/12-1024x464.png\" alt=\"\" class=\"wp-image-3254\" srcset=\"https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/12-1024x464.png 1024w, https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/12-300x136.png 300w, https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/12-768x348.png 768w, https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/12-1536x696.png 1536w, https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/12-18x8.png 18w, https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/12.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Um componente central desta iniciativa \u00e9 a estrat\u00e9gia de distribui\u00e7\u00e3o descentralizada da Reclone, constru\u00edda por meio de Hubs e Nodes interconectados em toda a Am\u00e9rica Latina. O Hub na Argentina e os Nodes no Brasil, Chile e Peru coordenar\u00e3o os envios para pa\u00edses vizinhos, reduzindo custos, simplificando processos alfandeg\u00e1rios e melhorando o acesso dos participantes em toda a regi\u00e3o.<\/p>\n\n\n\n<p>A iniciativa tamb\u00e9m destaca a import\u00e2ncia da colabora\u00e7\u00e3o regional na constru\u00e7\u00e3o de capacidades em biotecnologia. Muitos dos participantes selecionados j\u00e1 est\u00e3o envolvidos em a\u00e7\u00f5es de extens\u00e3o educacional, espa\u00e7os de ci\u00eancia comunit\u00e1ria, projetos de pesquisa locais ou iniciativas para democratizar o acesso a ferramentas cient\u00edficas em suas comunidades. Esperamos que os kits fortale\u00e7am essas iniciativas locais e criem novas oportunidades de colabora\u00e7\u00e3o al\u00e9m das fronteiras.<\/p>\n\n\n\n<p>Somos profundamente gratos a todos que se inscreveram no programa. A diversidade e a qualidade das inscri\u00e7\u00f5es tornaram o processo de sele\u00e7\u00e3o ao mesmo tempo desafiador e inspirador, destacando a for\u00e7a e o r\u00e1pido crescimento da comunidade de biotecnologia na Am\u00e9rica Latina.<\/p>\n\n\n\n<p>Esta iniciativa n\u00e3o teria sido poss\u00edvel sem o apoio da Chan Zuckerberg Initiative (CZI), cuja contribui\u00e7\u00e3o tem sido essencial para expandir o acesso a ferramentas de biotecnologia aberta, recursos educacionais e ci\u00eancia comunit\u00e1ria em toda a regi\u00e3o.<\/p>\n\n\n\n<p>Tamb\u00e9m agradecemos aos nossos parceiros e colaboradores na Am\u00e9rica Latina: Universidad Nacional de Cuyo, Pontificia Universidad Cat\u00f3lica de Chile, Universidade de S\u00e3o Paulo, Universidad Peruana Cayetano Heredia, SynBioBR e a rede CYTED RELARUS, pelo apoio na coordena\u00e7\u00e3o regional, colabora\u00e7\u00e3o e esfor\u00e7os de distribui\u00e7\u00e3o.<\/p>\n\n\n\n<p>Acompanhe a Reclone \u00e0 medida que esse movimento cresce! Siga-nos no\u00a0<a href=\"https:\/\/www.instagram.com\/reclone_org\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.linkedin.com\/company\/reclone\">LinkedIn<\/a>\u00a0para as \u00faltimas atualiza\u00e7\u00f5es e oportunidades de participa\u00e7\u00e3o.<\/p>\n\n\n<div class=\"tp-blockquote tpgb-relative-block tpgb-block-6a58_3267\"><div class=\"tpgb-blockquote-inner tpgb-quote-style-1\"><blockquote class=\"tpgb-quote-text\"><div class=\"quote-text-wrap\"><em>Entre em contato: <a>coordination@reclone.org<\/a><\/em><\/div><\/blockquote><\/div><\/div>\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Em mar\u00e7o de 2026, a Reclone lan\u00e7ou uma chamada aberta para os Latin America Starter Kits, com o objetivo de ampliar o acesso a ferramentas de biologia molecular, recursos educacionais e pr\u00e1ticas de biotecnologia aberta em toda a regi\u00e3o. Ap\u00f3s uma resposta expressiva da comunidade, com mais de 150 inscri\u00e7\u00f5es recebidas, temos o prazer de &#8230; <a title=\"Reclone Starter Kits ser\u00e3o distribu\u00eddos em 13 pa\u00edses da Am\u00e9rica Latina\" class=\"read-more\" href=\"https:\/\/reclone.org\/es\/reclone-starter-kits-serao-distribuidos-em-13-paises-da-america-latina\/\" aria-label=\"Leer m\u00e1s sobre Reclone Starter Kits ser\u00e3o distribu\u00eddos em 13 pa\u00edses da Am\u00e9rica Latina\">Leer m\u00e1s<\/a><\/p>","protected":false},"author":6230,"featured_media":3260,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"tpgb_global_settings":"","footnotes":""},"categories":[31],"tags":[],"research_categories":[],"region":[],"class_list":["post-3267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"tpgb_featured_images":{"full":["https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/LATAM-Starter-Kits-Campaign-Apresentacao-2.png",1024,768,false],"tp-image-grid":["https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/LATAM-Starter-Kits-Campaign-Apresentacao-2-700x700.png",700,700,true],"thumbnail":["https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/LATAM-Starter-Kits-Campaign-Apresentacao-2-150x150.png",150,150,true],"medium":["https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/LATAM-Starter-Kits-Campaign-Apresentacao-2-300x225.png",300,225,true],"medium_large":["https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/LATAM-Starter-Kits-Campaign-Apresentacao-2-768x576.png",768,576,true],"large":["https:\/\/reclone.org\/wp-content\/uploads\/2026\/05\/LATAM-Starter-Kits-Campaign-Apresentacao-2.png",1024,768,false],"default":"https:\/\/reclone.org\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"mayo 13, 2026","category_list":{"category":[{"term_id":31,"name":"Blog","slug":"blog","term_group":0,"term_taxonomy_id":31,"taxonomy":"category","description":"","parent":0,"count":12,"filter":"raw"}],"post_tag":false,"post_format":false,"people":false,"research_categories":false,"region":false},"author_name":"cibele","author_url":"https:\/\/reclone.org\/es\/author\/cibele\/","author_email":"cizolnier@gmail.com","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"","author_lastname":"","user_login":"cibele","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/763d83415a1d4e0dfc2f233ad85ec6d7abd49abfb47da9dd9192c70bfe8dfe64?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/763d83415a1d4e0dfc2f233ad85ec6d7abd49abfb47da9dd9192c70bfe8dfe64?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/763d83415a1d4e0dfc2f233ad85ec6d7abd49abfb47da9dd9192c70bfe8dfe64?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/reclone.org\/es\/category\/blog\/\" alt=\"Blog\" class=\"category-blog\">Blog<\/a> "},"_links":{"self":[{"href":"https:\/\/reclone.org\/es\/wp-json\/wp\/v2\/posts\/3267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reclone.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reclone.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reclone.org\/es\/wp-json\/wp\/v2\/users\/6230"}],"replies":[{"embeddable":true,"href":"https:\/\/reclone.org\/es\/wp-json\/wp\/v2\/comments?post=3267"}],"version-history":[{"count":3,"href":"https:\/\/reclone.org\/es\/wp-json\/wp\/v2\/posts\/3267\/revisions"}],"predecessor-version":[{"id":3273,"href":"https:\/\/reclone.org\/es\/wp-json\/wp\/v2\/posts\/3267\/revisions\/3273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reclone.org\/es\/wp-json\/wp\/v2\/media\/3260"}],"wp:attachment":[{"href":"https:\/\/reclone.org\/es\/wp-json\/wp\/v2\/media?parent=3267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reclone.org\/es\/wp-json\/wp\/v2\/categories?post=3267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reclone.org\/es\/wp-json\/wp\/v2\/tags?post=3267"},{"taxonomy":"research_categories","embeddable":true,"href":"https:\/\/reclone.org\/es\/wp-json\/wp\/v2\/research_categories?post=3267"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/reclone.org\/es\/wp-json\/wp\/v2\/region?post=3267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}